{"id":365,"count":1,"description":"","link":"https:\/\/igamemag.com\/en-gb\/tag\/network-en-gb\/","name":"network","slug":"network-en-gb","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>network Archives - iGame Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/igamemag.com\/en-gb\/tag\/network-en-gb\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"network Archives - iGame Magazine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/igamemag.com\/en-gb\/tag\/network-en-gb\/\" \/>\n<meta property=\"og:site_name\" content=\"iGame Magazine\" \/>\n<meta property=\"og:image\" content=\"https:\/\/igamemag.com\/wp-content\/uploads\/2025\/05\/igamemag-og-image-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@iGame_Mag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/tag\\\/network-en-gb\\\/\",\"url\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/tag\\\/network-en-gb\\\/\",\"name\":\"network Archives - iGame Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/tag\\\/network-en-gb\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/tag\\\/network-en-gb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"network\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/#website\",\"url\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/\",\"name\":\"iGame Magazine\",\"description\":\"Tech News &amp; Game Reviews\",\"publisher\":{\"@id\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/#organization\"},\"alternateName\":\"iGameMag\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/#organization\",\"name\":\"iGame Magazine Ltd\",\"alternateName\":\"iGameMag\",\"url\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/igamemag.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/iGame-Magazine-Official-Logo-Black.png\",\"contentUrl\":\"https:\\\/\\\/igamemag.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/iGame-Magazine-Official-Logo-Black.png\",\"width\":3654,\"height\":1012,\"caption\":\"iGame Magazine Ltd\"},\"image\":{\"@id\":\"https:\\\/\\\/igamemag.com\\\/en-gb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/iGameMagazine\\\/\",\"https:\\\/\\\/x.com\\\/iGame_Mag\",\"https:\\\/\\\/www.instagram.com\\\/igamemag\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@iGameMagazine\",\"https:\\\/\\\/www.tiktok.com\\\/@igamemag\",\"https:\\\/\\\/www.twitch.tv\\\/igamemagazine\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"network Archives - iGame Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/igamemag.com\/en-gb\/tag\/network-en-gb\/","og_locale":"en_GB","og_type":"article","og_title":"network Archives - iGame Magazine","og_url":"https:\/\/igamemag.com\/en-gb\/tag\/network-en-gb\/","og_site_name":"iGame Magazine","og_image":[{"width":1536,"height":1024,"url":"https:\/\/igamemag.com\/wp-content\/uploads\/2025\/05\/igamemag-og-image-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@iGame_Mag","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/igamemag.com\/en-gb\/tag\/network-en-gb\/","url":"https:\/\/igamemag.com\/en-gb\/tag\/network-en-gb\/","name":"network Archives - iGame Magazine","isPartOf":{"@id":"https:\/\/igamemag.com\/en-gb\/#website"},"breadcrumb":{"@id":"https:\/\/igamemag.com\/en-gb\/tag\/network-en-gb\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/igamemag.com\/en-gb\/tag\/network-en-gb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/igamemag.com\/en-gb\/"},{"@type":"ListItem","position":2,"name":"network"}]},{"@type":"WebSite","@id":"https:\/\/igamemag.com\/en-gb\/#website","url":"https:\/\/igamemag.com\/en-gb\/","name":"iGame Magazine","description":"Tech News &amp; Game Reviews","publisher":{"@id":"https:\/\/igamemag.com\/en-gb\/#organization"},"alternateName":"iGameMag","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/igamemag.com\/en-gb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/igamemag.com\/en-gb\/#organization","name":"iGame Magazine Ltd","alternateName":"iGameMag","url":"https:\/\/igamemag.com\/en-gb\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/igamemag.com\/en-gb\/#\/schema\/logo\/image\/","url":"https:\/\/igamemag.com\/wp-content\/uploads\/2025\/01\/iGame-Magazine-Official-Logo-Black.png","contentUrl":"https:\/\/igamemag.com\/wp-content\/uploads\/2025\/01\/iGame-Magazine-Official-Logo-Black.png","width":3654,"height":1012,"caption":"iGame Magazine Ltd"},"image":{"@id":"https:\/\/igamemag.com\/en-gb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iGameMagazine\/","https:\/\/x.com\/iGame_Mag","https:\/\/www.instagram.com\/igamemag\/","https:\/\/www.youtube.com\/@iGameMagazine","https:\/\/www.tiktok.com\/@igamemag","https:\/\/www.twitch.tv\/igamemagazine"]}]}},"_links":{"self":[{"href":"https:\/\/igamemag.com\/en-gb\/wp-json\/wp\/v2\/tags\/365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/igamemag.com\/en-gb\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/igamemag.com\/en-gb\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/igamemag.com\/en-gb\/wp-json\/wp\/v2\/posts?tags=365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}